{"id":78,"count":5,"description":"","link":"https:\/\/demo.shop123.lt\/dizainas-augalai\/kategorija\/kambariniai-augalai\/","name":"Kambariniai augalai","slug":"kambariniai-augalai","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/demo.shop123.lt\/dizainas-augalai\/wp-json\/wp\/v2\/product_cat\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.shop123.lt\/dizainas-augalai\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/demo.shop123.lt\/dizainas-augalai\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/demo.shop123.lt\/dizainas-augalai\/wp-json\/wp\/v2\/product?product_cat=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}